{"id":16236,"date":"2020-08-21T11:21:03","date_gmt":"2020-08-21T11:21:03","guid":{"rendered":"https:\/\/ps5.4800bps.com\/blog\/2020\/08\/21\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\/"},"modified":"2020-08-21T11:21:03","modified_gmt":"2020-08-21T11:21:03","slug":"deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and","status":"publish","type":"post","link":"https:\/\/ps5.4800bps.com\/blog\/2020\/08\/21\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\/","title":{"rendered":"Deathloop, GhostWire: Tokyo Developers Outline PS5 DualSense Features for Weapons and &#8230;"},"content":{"rendered":"<p>Deathloop, GhostWire: Tokyo Developers Outline PS5 DualSense Features for Weapons and Combat. Unjamming weapons in Deathloop and charging&amp;nbsp;&#8230;<br \/><a href=\"https:\/\/gamingbolt.com\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-for-weapons-and-combat\" target=\"_blank\" title=\"Deathloop, GhostWire: Tokyo Developers Outline PS5 DualSense Features for Weapons and ...\" rel=\"noopener noreferrer\"> View full source<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deathloop, GhostWire: Tokyo Developers Outline PS5 DualSense Features for Weapons and Combat. Unjamming weapons in [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":44324,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[222],"class_list":["post-16236","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-gamingbolt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Deathloop, GhostWire: Tokyo Developers Outline PS5 DualSense Features for Weapons and ... - PS5 News<\/title>\n<meta name=\"description\" content=\"Deathloop, GhostWire: Tokyo Developers Outline PS5 DualSense Features for Weapons and ... - PS5 News\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ps5.4800bps.com\/blog\/2020\/08\/21\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deathloop, GhostWire: Tokyo Developers Outline PS5 DualSense Features for Weapons and ... - PS5 News\" \/>\n<meta property=\"og:description\" content=\"Deathloop, GhostWire: Tokyo Developers Outline PS5 DualSense Features for Weapons and ... - PS5 News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ps5.4800bps.com\/blog\/2020\/08\/21\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\/\" \/>\n<meta property=\"og:site_name\" content=\"PS5 News\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-21T11:21:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ps5.4800bps.com\/blog\/wp-content\/uploads\/temp-4533.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"PS5 News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"PS5 News\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/2020\\\/08\\\/21\\\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/2020\\\/08\\\/21\\\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\\\/\"},\"author\":{\"name\":\"PS5 News\",\"@id\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/#\\\/schema\\\/person\\\/411717411e7434547b3eed8819da2e45\"},\"headline\":\"Deathloop, GhostWire: Tokyo Developers Outline PS5 DualSense Features for Weapons and &#8230;\",\"datePublished\":\"2020-08-21T11:21:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/2020\\\/08\\\/21\\\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\\\/\"},\"wordCount\":34,\"publisher\":{\"@id\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/#\\\/schema\\\/person\\\/411717411e7434547b3eed8819da2e45\"},\"image\":{\"@id\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/2020\\\/08\\\/21\\\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/wp-content\\\/uploads\\\/temp-4533.jpg\",\"keywords\":[\"GamingBolt\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/2020\\\/08\\\/21\\\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\\\/\",\"url\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/2020\\\/08\\\/21\\\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\\\/\",\"name\":\"Deathloop, GhostWire: Tokyo Developers Outline PS5 DualSense Features for Weapons and ... - PS5 News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/2020\\\/08\\\/21\\\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/2020\\\/08\\\/21\\\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/wp-content\\\/uploads\\\/temp-4533.jpg\",\"datePublished\":\"2020-08-21T11:21:03+00:00\",\"description\":\"Deathloop, GhostWire: Tokyo Developers Outline PS5 DualSense Features for Weapons and ... - PS5 News\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/2020\\\/08\\\/21\\\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/2020\\\/08\\\/21\\\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/2020\\\/08\\\/21\\\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/wp-content\\\/uploads\\\/temp-4533.jpg\",\"contentUrl\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/wp-content\\\/uploads\\\/temp-4533.jpg\",\"width\":2048,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/2020\\\/08\\\/21\\\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deathloop, GhostWire: Tokyo Developers Outline PS5 DualSense Features for Weapons and &#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/\",\"name\":\"PS5 News\",\"description\":\"Daily news about PS5 (Playstation 5) - fresh news, every day\",\"publisher\":{\"@id\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/#\\\/schema\\\/person\\\/411717411e7434547b3eed8819da2e45\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/#\\\/schema\\\/person\\\/411717411e7434547b3eed8819da2e45\",\"name\":\"PS5 News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7fcc4de55a1d680b79c62d551b53b1887264a590e48914bae550ef3072e08fe4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7fcc4de55a1d680b79c62d551b53b1887264a590e48914bae550ef3072e08fe4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7fcc4de55a1d680b79c62d551b53b1887264a590e48914bae550ef3072e08fe4?s=96&d=mm&r=g\",\"caption\":\"PS5 News\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7fcc4de55a1d680b79c62d551b53b1887264a590e48914bae550ef3072e08fe4?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/ps5.4800bps.com\\\/blog\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deathloop, GhostWire: Tokyo Developers Outline PS5 DualSense Features for Weapons and ... - PS5 News","description":"Deathloop, GhostWire: Tokyo Developers Outline PS5 DualSense Features for Weapons and ... - PS5 News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ps5.4800bps.com\/blog\/2020\/08\/21\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\/","og_locale":"en_US","og_type":"article","og_title":"Deathloop, GhostWire: Tokyo Developers Outline PS5 DualSense Features for Weapons and ... - PS5 News","og_description":"Deathloop, GhostWire: Tokyo Developers Outline PS5 DualSense Features for Weapons and ... - PS5 News","og_url":"https:\/\/ps5.4800bps.com\/blog\/2020\/08\/21\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\/","og_site_name":"PS5 News","article_published_time":"2020-08-21T11:21:03+00:00","og_image":[{"width":2048,"height":400,"url":"https:\/\/ps5.4800bps.com\/blog\/wp-content\/uploads\/temp-4533.jpg","type":"image\/jpeg"}],"author":"PS5 News","twitter_card":"summary_large_image","twitter_misc":{"Written by":"PS5 News"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ps5.4800bps.com\/blog\/2020\/08\/21\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\/#article","isPartOf":{"@id":"https:\/\/ps5.4800bps.com\/blog\/2020\/08\/21\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\/"},"author":{"name":"PS5 News","@id":"https:\/\/ps5.4800bps.com\/blog\/#\/schema\/person\/411717411e7434547b3eed8819da2e45"},"headline":"Deathloop, GhostWire: Tokyo Developers Outline PS5 DualSense Features for Weapons and &#8230;","datePublished":"2020-08-21T11:21:03+00:00","mainEntityOfPage":{"@id":"https:\/\/ps5.4800bps.com\/blog\/2020\/08\/21\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\/"},"wordCount":34,"publisher":{"@id":"https:\/\/ps5.4800bps.com\/blog\/#\/schema\/person\/411717411e7434547b3eed8819da2e45"},"image":{"@id":"https:\/\/ps5.4800bps.com\/blog\/2020\/08\/21\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\/#primaryimage"},"thumbnailUrl":"https:\/\/ps5.4800bps.com\/blog\/wp-content\/uploads\/temp-4533.jpg","keywords":["GamingBolt"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/ps5.4800bps.com\/blog\/2020\/08\/21\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\/","url":"https:\/\/ps5.4800bps.com\/blog\/2020\/08\/21\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\/","name":"Deathloop, GhostWire: Tokyo Developers Outline PS5 DualSense Features for Weapons and ... - PS5 News","isPartOf":{"@id":"https:\/\/ps5.4800bps.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ps5.4800bps.com\/blog\/2020\/08\/21\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\/#primaryimage"},"image":{"@id":"https:\/\/ps5.4800bps.com\/blog\/2020\/08\/21\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\/#primaryimage"},"thumbnailUrl":"https:\/\/ps5.4800bps.com\/blog\/wp-content\/uploads\/temp-4533.jpg","datePublished":"2020-08-21T11:21:03+00:00","description":"Deathloop, GhostWire: Tokyo Developers Outline PS5 DualSense Features for Weapons and ... - PS5 News","breadcrumb":{"@id":"https:\/\/ps5.4800bps.com\/blog\/2020\/08\/21\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ps5.4800bps.com\/blog\/2020\/08\/21\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ps5.4800bps.com\/blog\/2020\/08\/21\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\/#primaryimage","url":"https:\/\/ps5.4800bps.com\/blog\/wp-content\/uploads\/temp-4533.jpg","contentUrl":"https:\/\/ps5.4800bps.com\/blog\/wp-content\/uploads\/temp-4533.jpg","width":2048,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/ps5.4800bps.com\/blog\/2020\/08\/21\/deathloop-ghostwire-tokyo-developers-outline-ps5-dualsense-features-for-weapons-and\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ps5.4800bps.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Deathloop, GhostWire: Tokyo Developers Outline PS5 DualSense Features for Weapons and &#8230;"}]},{"@type":"WebSite","@id":"https:\/\/ps5.4800bps.com\/blog\/#website","url":"https:\/\/ps5.4800bps.com\/blog\/","name":"PS5 News","description":"Daily news about PS5 (Playstation 5) - fresh news, every day","publisher":{"@id":"https:\/\/ps5.4800bps.com\/blog\/#\/schema\/person\/411717411e7434547b3eed8819da2e45"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ps5.4800bps.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/ps5.4800bps.com\/blog\/#\/schema\/person\/411717411e7434547b3eed8819da2e45","name":"PS5 News","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/7fcc4de55a1d680b79c62d551b53b1887264a590e48914bae550ef3072e08fe4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7fcc4de55a1d680b79c62d551b53b1887264a590e48914bae550ef3072e08fe4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7fcc4de55a1d680b79c62d551b53b1887264a590e48914bae550ef3072e08fe4?s=96&d=mm&r=g","caption":"PS5 News"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/7fcc4de55a1d680b79c62d551b53b1887264a590e48914bae550ef3072e08fe4?s=96&d=mm&r=g"},"sameAs":["https:\/\/ps5.4800bps.com\/blog\/"]}]}},"_links":{"self":[{"href":"https:\/\/ps5.4800bps.com\/blog\/wp-json\/wp\/v2\/posts\/16236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ps5.4800bps.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ps5.4800bps.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ps5.4800bps.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ps5.4800bps.com\/blog\/wp-json\/wp\/v2\/comments?post=16236"}],"version-history":[{"count":0,"href":"https:\/\/ps5.4800bps.com\/blog\/wp-json\/wp\/v2\/posts\/16236\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ps5.4800bps.com\/blog\/wp-json\/wp\/v2\/media\/44324"}],"wp:attachment":[{"href":"https:\/\/ps5.4800bps.com\/blog\/wp-json\/wp\/v2\/media?parent=16236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ps5.4800bps.com\/blog\/wp-json\/wp\/v2\/categories?post=16236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ps5.4800bps.com\/blog\/wp-json\/wp\/v2\/tags?post=16236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}